{"id":1237,"date":"2014-05-15T16:53:21","date_gmt":"2014-05-15T20:53:21","guid":{"rendered":"http:\/\/michaelchong.ca\/fr\/?p=1237"},"modified":"2014-05-15T16:53:21","modified_gmt":"2014-05-15T20:53:21","slug":"michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes","status":"publish","type":"post","link":"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/","title":{"rendered":"Michael Chong pr\u00e9sente une nouvelle version de la Loi instituant des r\u00e9formes"},"content":{"rendered":"<p>POUR DIFFUSION IMM\u00c9DIATE\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Le 7 avril 2014<\/p>\n<p><strong>Michael Chong pr\u00e9sente une nouvelle version de la Loi instituant des r\u00e9formes<em><\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Tenant compte des commentaires re\u00e7us des Canadiens et des d\u00e9put\u00e9s, une version modifi\u00e9e de la Loi instituant des r\u00e9formes a \u00e9t\u00e9 pr\u00e9sent\u00e9e \u00e0 la Chambre des communes aujourd\u2019hui.<\/em><\/strong><br \/>\nOTTAWA \u2013 Michael Chong, d\u00e9put\u00e9 de Wellington\u2014Halton Hills, a d\u00e9pos\u00e9 aujourd\u2019hui une version modifi\u00e9e de son projet de loi d\u2019initiative parlementaire, la <em>Loi instituant des r\u00e9formes<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p>Depuis son d\u00e9p\u00f4t, en d\u00e9cembre dernier, nombre de d\u00e9bats et discussions ont \u00e9t\u00e9 men\u00e9s au sujet de la <em>Loi instituant des r\u00e9formes<\/em>. Beaucoup de Canadiens, y compris des d\u00e9put\u00e9s, ont fait des suggestions \u00e0 l\u2019\u00e9gard du projet de loi. En tenant compte de ces suggestions, des amendements ont \u00e9t\u00e9 apport\u00e9s au projet de loi. Le titre abr\u00e9g\u00e9 du projet de loi pr\u00e9sent\u00e9 aujourd\u2019hui est <em>Loi de 2014 instituant des r\u00e9formes<\/em>, afin de marquer la distinction par rapport au projet de loi original, d\u00e9pos\u00e9 en d\u00e9cembre, qui \u00e9tait appel\u00e9 <em>Loi de 2013 instituant des r\u00e9formes<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p>Le projet de loi modifi\u00e9 se fonde sur les m\u00eames principes que ceux de l\u2019original : il r\u00e9tablit le contr\u00f4le local sur l\u2019investiture des partis, pr\u00e9voit que l\u2019\u00e9lection du pr\u00e9sident du groupe parlementaire et l\u2019expulsion de membres du groupe parlementaire se feront par voie de scrutin au sein du groupe parlementaire, et d\u00e9finit les r\u00e8gles relatives \u00e0 l\u2019examen de la direction du parti par le groupe parlementaire.<\/p>\n<p>&nbsp;<\/p>\n<p>Les amendements font passer la proportion de d\u00e9put\u00e9s du groupe parlementaire requise pour tenir un vote d\u2019examen de 15 \u00e0 20\u00a0%, exigent que les noms de ceux qui demandent un vote d\u2019examen soient rendus publics, red\u00e9finissent la notion de majorit\u00e9 des voix pour un examen de telle sorte qu\u2019elle s\u2019applique \u00e0 l\u2019ensemble du groupe parlementaire plut\u00f4t qu\u2019aux d\u00e9put\u00e9s pr\u00e9sents \u00e0 la r\u00e9union, remplacent l\u2019agent \u00e0 l\u2019investiture nomm\u00e9 localement pour chaque association de circonscription par un agent pour chaque province et les territoires, maintiennent le pouvoir des chefs de parti de radier une association de circonscription et assujettissent les r\u00e8gles d\u2019examen des directions de parti \u00e0 la <em>Loi sur le Parlement du Canada<\/em>, plut\u00f4t qu\u2019\u00e0 la <em>Loi \u00e9lectorale du Canada<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab\u00a0Lorsque la <em>Loi instituant des r\u00e9formes<\/em> a \u00e9t\u00e9 pr\u00e9sent\u00e9e en d\u00e9cembre dernier, j\u2019ai re\u00e7u favorablement les commentaires et les suggestions. En tenant compte de ces suggestions, une version modifi\u00e9e du projet de loi a \u00e9t\u00e9 d\u00e9pos\u00e9e. Je tiens \u00e0 remercier tous ceux qui ont formul\u00e9 des propositions pour am\u00e9liorer le projet de loi\u00a0\u00bb, a d\u00e9clar\u00e9 M. Chong.<\/p>\n<p>&nbsp;<\/p>\n<p>Il ajoute\u00a0: \u00ab\u00a0Nous devons r\u00e9former le Parlement pour mieux l\u2019adapter aux besoins des Canadiens. C\u2019est exactement ce que fera la <em>Loi de 2014 instituant des r\u00e9formes<\/em>. Elle renforcera la repr\u00e9sentativit\u00e9 et la responsabilit\u00e9 des d\u00e9put\u00e9s \u00e0 l\u2019\u00e9gard des Canadiens.\u00a0\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>Comme dans le cas du projet de loi original, M. James Rajotte, d\u00e9put\u00e9 d\u2019Edmonton\u2014Leduc, a appuy\u00e9 la <em>Loi de 2014 instituant des r\u00e9formes<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\">-30-<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>POUR DIFFUSION IMM\u00c9DIATE\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Le 7 avril 2014 Michael Chong pr\u00e9sente une nouvelle version de la Loi instituant des r\u00e9formes &nbsp; Tenant compte des commentaires re\u00e7us des Canadiens et des d\u00e9put\u00e9s, une version modifi\u00e9e de la Loi instituant des r\u00e9formes a \u00e9t\u00e9 pr\u00e9sent\u00e9e \u00e0 la Chambre des communes aujourd\u2019hui. OTTAWA \u2013 Michael Chong, d\u00e9put\u00e9 de Wellington\u2014Halton <a href=\"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/\" class=\"more-link\">&#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[20],"tags":[],"class_list":["post-1237","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Michael Chong pr\u00e9sente une nouvelle version de la Loi instituant des r\u00e9formes - Michael Chong<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Michael Chong pr\u00e9sente une nouvelle version de la Loi instituant des r\u00e9formes - Michael Chong\" \/>\n<meta property=\"og:description\" content=\"POUR DIFFUSION IMM\u00c9DIATE\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Le 7 avril 2014 Michael Chong pr\u00e9sente une nouvelle version de la Loi instituant des r\u00e9formes &nbsp; Tenant compte des commentaires re\u00e7us des Canadiens et des d\u00e9put\u00e9s, une version modifi\u00e9e de la Loi instituant des r\u00e9formes a \u00e9t\u00e9 pr\u00e9sent\u00e9e \u00e0 la Chambre des communes aujourd\u2019hui. OTTAWA \u2013 Michael Chong, d\u00e9put\u00e9 de Wellington\u2014Halton ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/\" \/>\n<meta property=\"og:site_name\" content=\"Michael Chong\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-15T20:53:21+00:00\" \/>\n<meta name=\"author\" content=\"admin437\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin437\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/\"},\"author\":{\"name\":\"admin437\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/f402ec3bbb11ca1e513f4971ab697c81\"},\"headline\":\"Michael Chong pr\u00e9sente une nouvelle version de la Loi instituant des r\u00e9formes\",\"datePublished\":\"2014-05-15T20:53:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/\"},\"wordCount\":566,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/#organization\"},\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/\",\"url\":\"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/\",\"name\":\"Michael Chong pr\u00e9sente une nouvelle version de la Loi instituant des r\u00e9formes - Michael Chong\",\"isPartOf\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/#website\"},\"datePublished\":\"2014-05-15T20:53:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/michaelchong.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Michael Chong pr\u00e9sente une nouvelle version de la Loi instituant des r\u00e9formes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#website\",\"url\":\"https:\/\/michaelchong.ca\/fr\/\",\"name\":\"Michael Chong\",\"description\":\"D\u00e9put\u00e9 de Wellington-Halton Hills-Nord\",\"publisher\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/michaelchong.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#organization\",\"name\":\"Michael Chong\",\"url\":\"https:\/\/michaelchong.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/michaelchong.ca\/fr\/wp-content\/uploads\/2025\/05\/michael-chong-logo-2025-white-fr-1.png\",\"contentUrl\":\"https:\/\/michaelchong.ca\/fr\/wp-content\/uploads\/2025\/05\/michael-chong-logo-2025-white-fr-1.png\",\"width\":1142,\"height\":255,\"caption\":\"Michael Chong\"},\"image\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/f402ec3bbb11ca1e513f4971ab697c81\",\"name\":\"admin437\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ed1357ca834555c038a49b5887555419479fc5d6ebebc7ac134ff0131bbfa389?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ed1357ca834555c038a49b5887555419479fc5d6ebebc7ac134ff0131bbfa389?s=96&d=mm&r=g\",\"caption\":\"admin437\"},\"sameAs\":[\"http:\/\/michaelchong.ca\/fr\"],\"url\":\"https:\/\/michaelchong.ca\/fr\/author\/admin437\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Michael Chong pr\u00e9sente une nouvelle version de la Loi instituant des r\u00e9formes - Michael Chong","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/","og_locale":"fr_CA","og_type":"article","og_title":"Michael Chong pr\u00e9sente une nouvelle version de la Loi instituant des r\u00e9formes - Michael Chong","og_description":"POUR DIFFUSION IMM\u00c9DIATE\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Le 7 avril 2014 Michael Chong pr\u00e9sente une nouvelle version de la Loi instituant des r\u00e9formes &nbsp; Tenant compte des commentaires re\u00e7us des Canadiens et des d\u00e9put\u00e9s, une version modifi\u00e9e de la Loi instituant des r\u00e9formes a \u00e9t\u00e9 pr\u00e9sent\u00e9e \u00e0 la Chambre des communes aujourd\u2019hui. OTTAWA \u2013 Michael Chong, d\u00e9put\u00e9 de Wellington\u2014Halton ...","og_url":"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/","og_site_name":"Michael Chong","article_published_time":"2014-05-15T20:53:21+00:00","author":"admin437","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin437","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/#article","isPartOf":{"@id":"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/"},"author":{"name":"admin437","@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/f402ec3bbb11ca1e513f4971ab697c81"},"headline":"Michael Chong pr\u00e9sente une nouvelle version de la Loi instituant des r\u00e9formes","datePublished":"2014-05-15T20:53:21+00:00","mainEntityOfPage":{"@id":"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/"},"wordCount":566,"commentCount":0,"publisher":{"@id":"https:\/\/michaelchong.ca\/fr\/#organization"},"articleSection":["Nouvelles"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/","url":"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/","name":"Michael Chong pr\u00e9sente une nouvelle version de la Loi instituant des r\u00e9formes - Michael Chong","isPartOf":{"@id":"https:\/\/michaelchong.ca\/fr\/#website"},"datePublished":"2014-05-15T20:53:21+00:00","breadcrumb":{"@id":"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/michaelchong.ca\/fr\/2014\/05\/15\/michael-chong-presente-une-nouvelle-version-de-la-loi-instituant-des-reformes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/michaelchong.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Michael Chong pr\u00e9sente une nouvelle version de la Loi instituant des r\u00e9formes"}]},{"@type":"WebSite","@id":"https:\/\/michaelchong.ca\/fr\/#website","url":"https:\/\/michaelchong.ca\/fr\/","name":"Michael Chong","description":"D\u00e9put\u00e9 de Wellington-Halton Hills-Nord","publisher":{"@id":"https:\/\/michaelchong.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/michaelchong.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/michaelchong.ca\/fr\/#organization","name":"Michael Chong","url":"https:\/\/michaelchong.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/michaelchong.ca\/fr\/wp-content\/uploads\/2025\/05\/michael-chong-logo-2025-white-fr-1.png","contentUrl":"https:\/\/michaelchong.ca\/fr\/wp-content\/uploads\/2025\/05\/michael-chong-logo-2025-white-fr-1.png","width":1142,"height":255,"caption":"Michael Chong"},"image":{"@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/f402ec3bbb11ca1e513f4971ab697c81","name":"admin437","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ed1357ca834555c038a49b5887555419479fc5d6ebebc7ac134ff0131bbfa389?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed1357ca834555c038a49b5887555419479fc5d6ebebc7ac134ff0131bbfa389?s=96&d=mm&r=g","caption":"admin437"},"sameAs":["http:\/\/michaelchong.ca\/fr"],"url":"https:\/\/michaelchong.ca\/fr\/author\/admin437\/"}]}},"_links":{"self":[{"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/posts\/1237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/comments?post=1237"}],"version-history":[{"count":0,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/posts\/1237\/revisions"}],"wp:attachment":[{"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/media?parent=1237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/categories?post=1237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/tags?post=1237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}