{"id":1279,"date":"2015-06-23T22:50:12","date_gmt":"2015-06-24T02:50:12","guid":{"rendered":"http:\/\/michaelchong.ca\/fr\/?p=1279"},"modified":"2015-06-23T22:50:12","modified_gmt":"2015-06-24T02:50:12","slug":"loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14","status":"publish","type":"post","link":"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/","title":{"rendered":"Loi sur la r\u00e9forme, 2014 est adopt\u00e9 par le S\u00e9nat, 38-14"},"content":{"rendered":"<p><em><span style=\"font-size: small;\">Loi sur la r\u00e9forme\u00a02014 sera en vigueur sept jours apr\u00e8s la prochaine \u00e9lection g\u00e9n\u00e9rale<\/span><\/em><\/p>\n<p><span style=\"font-size: small;\">\u00a0OTTAWA \u2014 Plus t\u00f4t ce soir, le S\u00e9nat du Canada a adopt\u00e9 la <em>Loi sur la r\u00e9forme, 2014<\/em> 38 \u00e0 14. La <em>loi sur la r\u00e9forme<\/em> entrera en vigueur sept jours apr\u00e8s la prochaine \u00e9lection g\u00e9n\u00e9rale.<\/span><\/p>\n<p><span style=\"font-size: small;\">\u00ab\u00a0Le passage de la <em>loi sur la r\u00e9forme<\/em> est une victoire pour la d\u00e9mocratie. Les Canadiens ont parl\u00e9 par les dizaines de milliers et les d\u00e9put\u00e9s ont r\u00e9agi en votant pour le projet de loi. <em>La loi sur la r\u00e9forme<\/em> d\u00e9montre que le parlement est capable de r\u00e9forme et de renouveau\u00a0\u00bb, a d\u00e9clar\u00e9 Chong.<\/span><\/p>\n<p><span style=\"font-size: small;\">La <em>loi sur la r\u00e9forme<\/em> a \u00e9t\u00e9 introduite en d\u00e9cembre 2013 et adopt\u00e9e avec une \u00e9crasante majorit\u00e9 par la Chambre des communes, 260\u00a0\u00e017, le 25 f\u00e9vrier 2015.<\/span><\/p>\n<p><span style=\"font-size: small;\">La <em>loi sur la r\u00e9forme<\/em> apportera des modifications \u00e0 la <em>Loi sur le parlement du Canada<\/em> et la <em>Loi \u00e9lectorale du Canada<\/em>. La <em>loi sur la r\u00e9forme<\/em> supprimera l\u2019obligation statutaire, en place depuis 1970, qui exige que les chefs approuvent les candidats du parti. Elle permettra aux d\u00e9put\u00e9s de d\u00e9cider si le chef ou caucus peut expulser les d\u00e9put\u00e9s du caucus et comment le pr\u00e9sident du caucus est s\u00e9lectionn\u00e9. Cela permettra aux d\u00e9put\u00e9s de choisir un chef int\u00e9rimaire, en cas de soudaine d\u00e9mission, d\u2019emp\u00eachement ou de d\u00e9c\u00e8s du chef. Enfin, il permettra aux d\u00e9put\u00e9s de formaliser les r\u00e8gles d\u2019examiner et de retirer les chefs de parti, cr\u00e9ant un processus plus ordonn\u00e9 que le chaos qui peut en r\u00e9sulter quand un caucus perd confiance en son chef.<\/span><\/p>\n<p><span style=\"font-size: small;\">\u00ab\u00a0La <em>loi sur la r\u00e9forme<\/em> traitera un probl\u00e8me de longue date \u00e0 Ottawa\u00a0: la concentration du pouvoir que poss\u00e8dent les chefs de parti, y compris le premier ministre. Il donnera \u00e0 certains membres individuels du parlement plus de pouvoirs pour repr\u00e9senter leurs \u00e9lecteurs et les Canadiens\u00a0\u00bb, a d\u00e9clar\u00e9 Chong.<\/span><\/p>\n<p><span style=\"font-size: small;\">\u00ab\u00a0Je tiens \u00e0 remercier mes coll\u00e8gues \u00e0 la Chambre des communes et au S\u00e9nat qui ont appuy\u00e9 ce projet de loi. En particulier, je tiens \u00e0 remercier le d\u00e9put\u00e9 James Rajotte, qui a appuy\u00e9 le projet de loi dans les Communes, et le s\u00e9nateur Scott Tannas, qui a parrain\u00e9 le projet de loi au S\u00e9nat\u00a0\u00bb, a d\u00e9clar\u00e9 Chong. \u00ab\u00a0Mais surtout, je tiens \u00e0 remercier les dizaines de milliers de Canadiens qui ont communiqu\u00e9 avec leur d\u00e9put\u00e9 local et les s\u00e9nateurs pour exprimer leur soutien pour ces r\u00e9formes. Sans leur soutien, ce projet de loi ne serait jamais devenu une loi\u00a0\u00bb.<\/span><\/p>\n<p><span style=\"font-size: small;\">La <em>loi sur la r\u00e9forme<\/em> est r\u00e9gl\u00e9e pour recevoir la sanction royale dans les prochains jours.<\/span><\/p>\n<p align=\"center\"><span style=\"font-size: small;\">\u2014 30 \u2014<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Loi sur la r\u00e9forme\u00a02014 sera en vigueur sept jours apr\u00e8s la prochaine \u00e9lection g\u00e9n\u00e9rale \u00a0OTTAWA \u2014 Plus t\u00f4t ce soir, le S\u00e9nat du Canada a adopt\u00e9 la Loi sur la r\u00e9forme, 2014 38 \u00e0 14. La loi sur la r\u00e9forme entrera en vigueur sept jours apr\u00e8s la prochaine \u00e9lection g\u00e9n\u00e9rale. \u00ab\u00a0Le passage de la loi <a href=\"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/\" class=\"more-link\">&#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[20],"tags":[],"class_list":["post-1279","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Loi sur la r\u00e9forme, 2014 est adopt\u00e9 par le S\u00e9nat, 38-14 - Michael Chong<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Loi sur la r\u00e9forme, 2014 est adopt\u00e9 par le S\u00e9nat, 38-14 - Michael Chong\" \/>\n<meta property=\"og:description\" content=\"Loi sur la r\u00e9forme\u00a02014 sera en vigueur sept jours apr\u00e8s la prochaine \u00e9lection g\u00e9n\u00e9rale \u00a0OTTAWA \u2014 Plus t\u00f4t ce soir, le S\u00e9nat du Canada a adopt\u00e9 la Loi sur la r\u00e9forme, 2014 38 \u00e0 14. La loi sur la r\u00e9forme entrera en vigueur sept jours apr\u00e8s la prochaine \u00e9lection g\u00e9n\u00e9rale. \u00ab\u00a0Le passage de la loi ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Michael Chong\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-24T02:50:12+00:00\" \/>\n<meta name=\"author\" content=\"admin437\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin437\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/\"},\"author\":{\"name\":\"admin437\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/f402ec3bbb11ca1e513f4971ab697c81\"},\"headline\":\"Loi sur la r\u00e9forme, 2014 est adopt\u00e9 par le S\u00e9nat, 38-14\",\"datePublished\":\"2015-06-24T02:50:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/\"},\"wordCount\":482,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/#organization\"},\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/\",\"url\":\"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/\",\"name\":\"Loi sur la r\u00e9forme, 2014 est adopt\u00e9 par le S\u00e9nat, 38-14 - Michael Chong\",\"isPartOf\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/#website\"},\"datePublished\":\"2015-06-24T02:50:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/michaelchong.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loi sur la r\u00e9forme, 2014 est adopt\u00e9 par le S\u00e9nat, 38-14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#website\",\"url\":\"https:\/\/michaelchong.ca\/fr\/\",\"name\":\"Michael Chong\",\"description\":\"D\u00e9put\u00e9 de Wellington-Halton Hills-Nord\",\"publisher\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/michaelchong.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#organization\",\"name\":\"Michael Chong\",\"url\":\"https:\/\/michaelchong.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/michaelchong.ca\/fr\/wp-content\/uploads\/2025\/05\/michael-chong-logo-2025-white-fr-1.png\",\"contentUrl\":\"https:\/\/michaelchong.ca\/fr\/wp-content\/uploads\/2025\/05\/michael-chong-logo-2025-white-fr-1.png\",\"width\":1142,\"height\":255,\"caption\":\"Michael Chong\"},\"image\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/f402ec3bbb11ca1e513f4971ab697c81\",\"name\":\"admin437\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ed1357ca834555c038a49b5887555419479fc5d6ebebc7ac134ff0131bbfa389?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ed1357ca834555c038a49b5887555419479fc5d6ebebc7ac134ff0131bbfa389?s=96&d=mm&r=g\",\"caption\":\"admin437\"},\"sameAs\":[\"http:\/\/michaelchong.ca\/fr\"],\"url\":\"https:\/\/michaelchong.ca\/fr\/author\/admin437\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Loi sur la r\u00e9forme, 2014 est adopt\u00e9 par le S\u00e9nat, 38-14 - Michael Chong","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/","og_locale":"fr_CA","og_type":"article","og_title":"Loi sur la r\u00e9forme, 2014 est adopt\u00e9 par le S\u00e9nat, 38-14 - Michael Chong","og_description":"Loi sur la r\u00e9forme\u00a02014 sera en vigueur sept jours apr\u00e8s la prochaine \u00e9lection g\u00e9n\u00e9rale \u00a0OTTAWA \u2014 Plus t\u00f4t ce soir, le S\u00e9nat du Canada a adopt\u00e9 la Loi sur la r\u00e9forme, 2014 38 \u00e0 14. La loi sur la r\u00e9forme entrera en vigueur sept jours apr\u00e8s la prochaine \u00e9lection g\u00e9n\u00e9rale. \u00ab\u00a0Le passage de la loi ...","og_url":"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/","og_site_name":"Michael Chong","article_published_time":"2015-06-24T02:50:12+00:00","author":"admin437","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin437","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/#article","isPartOf":{"@id":"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/"},"author":{"name":"admin437","@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/f402ec3bbb11ca1e513f4971ab697c81"},"headline":"Loi sur la r\u00e9forme, 2014 est adopt\u00e9 par le S\u00e9nat, 38-14","datePublished":"2015-06-24T02:50:12+00:00","mainEntityOfPage":{"@id":"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/"},"wordCount":482,"commentCount":0,"publisher":{"@id":"https:\/\/michaelchong.ca\/fr\/#organization"},"articleSection":["Nouvelles"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/","url":"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/","name":"Loi sur la r\u00e9forme, 2014 est adopt\u00e9 par le S\u00e9nat, 38-14 - Michael Chong","isPartOf":{"@id":"https:\/\/michaelchong.ca\/fr\/#website"},"datePublished":"2015-06-24T02:50:12+00:00","breadcrumb":{"@id":"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/michaelchong.ca\/fr\/2015\/06\/23\/loi-sur-la-reforme-2014-est-adopte-par-le-senat-38-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/michaelchong.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Loi sur la r\u00e9forme, 2014 est adopt\u00e9 par le S\u00e9nat, 38-14"}]},{"@type":"WebSite","@id":"https:\/\/michaelchong.ca\/fr\/#website","url":"https:\/\/michaelchong.ca\/fr\/","name":"Michael Chong","description":"D\u00e9put\u00e9 de Wellington-Halton Hills-Nord","publisher":{"@id":"https:\/\/michaelchong.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/michaelchong.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/michaelchong.ca\/fr\/#organization","name":"Michael Chong","url":"https:\/\/michaelchong.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/michaelchong.ca\/fr\/wp-content\/uploads\/2025\/05\/michael-chong-logo-2025-white-fr-1.png","contentUrl":"https:\/\/michaelchong.ca\/fr\/wp-content\/uploads\/2025\/05\/michael-chong-logo-2025-white-fr-1.png","width":1142,"height":255,"caption":"Michael Chong"},"image":{"@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/f402ec3bbb11ca1e513f4971ab697c81","name":"admin437","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ed1357ca834555c038a49b5887555419479fc5d6ebebc7ac134ff0131bbfa389?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed1357ca834555c038a49b5887555419479fc5d6ebebc7ac134ff0131bbfa389?s=96&d=mm&r=g","caption":"admin437"},"sameAs":["http:\/\/michaelchong.ca\/fr"],"url":"https:\/\/michaelchong.ca\/fr\/author\/admin437\/"}]}},"_links":{"self":[{"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/posts\/1279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/comments?post=1279"}],"version-history":[{"count":0,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/posts\/1279\/revisions"}],"wp:attachment":[{"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/media?parent=1279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/categories?post=1279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/tags?post=1279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}