{"id":1427,"date":"2019-02-22T15:44:35","date_gmt":"2019-02-22T20:44:35","guid":{"rendered":"http:\/\/michaelchong.ca\/fr\/?p=1427"},"modified":"2019-02-22T15:44:35","modified_gmt":"2019-02-22T20:44:35","slug":"conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache","status":"publish","type":"post","link":"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/","title":{"rendered":"Conseils \u00e0 l\u2019intention des voyageurs canadiens : Voyager avec des enfants pendant la semaine de rel\u00e2che"},"content":{"rendered":"<p>Le 13 f\u00e9vrier 2019 \u2013 Ottawa (Ontario) \u2013 Affaires mondiales Canada<\/p>\n<p>Dans les semaines \u00e0 venir, de nombreuses familles canadiennes profiteront du cong\u00e9 scolaire pour se rendre dans une destination internationale. Le gouvernement du Canada veut encourager tous les voyageurs \u00e0 bien s\u2019informer afin qu\u2019ils puissent passer un s\u00e9jour agr\u00e9able et en toute s\u00e9curit\u00e9 \u00e0 l\u2019\u00e9tranger.<\/p>\n<p>Lorsque vous planifiez voyager avec des enfants, tenez compte des conseils suivants:<\/p>\n<ol>\n<li><strong>Ayez les documents requis\u00a0:<\/strong>\u00a0Tous les enfants doivent \u00eatre munis d\u2019un passeport canadien valide lorsqu\u2019ils voyagent \u00e0 l\u2019\u00e9tranger. Si un enfant voyage seul, avec un seul parent ou avec quelqu\u2019un d\u2019autre, il doit poss\u00e9der une\u00a0<a href=\"https:\/\/voyage.gc.ca\/voyager\/enfant\/lettre-de-consentement\">lettre de consentement<\/a>\u00a0qui prouve que l\u2019enfant a obtenu la permission de voyager \u00e0 l\u2019\u00e9tranger. Les enfants peuvent aussi avoir besoin de documents d\u2019identification suppl\u00e9mentaires, tels un certificat de naissance, un certificat de citoyennet\u00e9 ou d\u2019autres documents l\u00e9gaux, comme des documents de divorce, les ordonnances de garde d\u2019un tribunal ou un certificat de d\u00e9c\u00e8s (si l\u2019un des parents est d\u00e9c\u00e9d\u00e9).<\/li>\n<li><strong>Assurez-vous que tous les membres de la famille obtiennent les vaccins et les m\u00e9dicaments de voyage recommand\u00e9s<\/strong>\u00a0<strong>:<\/strong>\u00a0Visitez une clinique au moins six semaines avant votre d\u00e9part et consultez le site Web Voyage.gc.ca pour des\u00a0<a href=\"https:\/\/voyage.gc.ca\/voyager\/sante-securite\/enfants\">conseils sant\u00e9 pour voyager avec des enfants<\/a>. En g\u00e9n\u00e9ral, il y a un risque plus \u00e9lev\u00e9 de contracter la plupart des maladies \u00e9vitables par la vaccination en voyageant \u00e0 l\u2019\u00e9tranger. Ces maladies sont habituellement plus graves chez les enfants que chez les adultes. Il se peut que le calendrier de vaccination de votre enfant ait besoin d\u2019\u00eatre r\u00e9vis\u00e9 afin que ce dernier soit bien prot\u00e9g\u00e9.<\/li>\n<li><strong>Au cas o\u00f9 votre enfant se perde\u00a0:<\/strong>\u00a0Pensez \u00e0 placer une copie de leur identification personnelle et des num\u00e9ros d\u2019urgence dans sa poche. Essayez aussi d\u2019avoir une photo r\u00e9cente de votre enfant avec vous. Si votre enfant se perd, communiquez avec la police locale et\u00a0<a href=\"https:\/\/voyage.gc.ca\/assistance\/ambassades-consulats\">l\u2019ambassade ou le consulat du Canada le plus pr\u00e8s \u00e0 l\u2019\u00e9tranger<\/a>.<\/li>\n<li><strong>Pr\u00e9parez-vous \u00e0 passer les contr\u00f4les de s\u00e9curit\u00e9 de fa\u00e7on efficace<\/strong>\u00a0<strong>:<\/strong>\u00a0Tenez votre enfant dans vos bras pour franchir le portique de d\u00e9tection de m\u00e9tal, mais laissez votre enfant le franchir seul s\u2019il est capable de le faire. Pour conna\u00eetre ce qu\u2019on peut apporter dans le bagage de cabine de votre enfant, lisez les conseils pour\u00a0<a href=\"https:\/\/voyage.gc.ca\/avion\/enfants-controle-de-securite\">passer au contr\u00f4le de s\u00fbret\u00e9 avec de jeunes enfants<\/a>.<\/li>\n<li><strong>Si votre enfant voyage seul en avion\u00a0:<\/strong>\u00a0Confirmez aupr\u00e8s de la compagnie a\u00e9rienne que ses employ\u00e9s pourront accompagner et surveiller votre enfant depuis l\u2019enregistrement jusqu\u2019\u00e0 l\u2019arriv\u00e9e, et v\u00e9rifiez les limites d\u2019\u00e2ge ou autres restrictions de vol pour les enfants voyageant seuls. De m\u00eame, assurez-vous qu\u2019un parent ou tuteur reste \u00e0 l\u2019a\u00e9roport tant que l\u2019avion dans lequel se trouve l\u2019enfant n\u2019aura pas d\u00e9coll\u00e9 et que la personne qui accueille l\u2019enfant \u00e0 son arriv\u00e9e est munie de pi\u00e8ces d\u2019identification et d\u2019autorisation appropri\u00e9es.<\/li>\n<\/ol>\n<p>Avant de quitter le pays pour une destination internationale, tous les Canadiens devraient aussi:<\/p>\n<ol>\n<li><strong>S\u2019informer.\u00a0<\/strong>Avant de quitter le Canada, consultez les\u00a0<a href=\"https:\/\/voyage.gc.ca\/voyager\/avertissements\">Conseils aux voyageurs et avertissements<\/a>\u00a0pour obtenir de l\u2019information d\u00e9taill\u00e9e sur le pays de destination.<\/li>\n<li><strong>Se procurer une assurance voyage.<\/strong>\u00a0<a href=\"https:\/\/voyage.gc.ca\/voyager\/documents\/assurance-voyage\">L\u2019assurance voyage<\/a>\u00a0devrait inclure une assurance maladie, une assurance vie et une assurance invalidit\u00e9 qui aideront \u00e0 \u00e9viter des d\u00e9penses importantes, comme les frais d\u2019hospitalisation ou de traitements m\u00e9dicaux \u00e0 l\u2019ext\u00e9rieur du Canada.<\/li>\n<li><strong>S\u2019inscrire\u00a0<\/strong>aupr\u00e8s du service d\u2019<a href=\"https:\/\/voyage.gc.ca\/voyager\/inscription\">Inscription des Canadiens \u00e0 l\u2019\u00e9tranger<\/a>\u00a0pour recevoir les derni\u00e8res mises \u00e0 jour en cas d\u2019urgence \u00e0 l\u2019\u00e9tranger ou d\u2019urgence personnelle \u00e0 la maison.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>Les Canadiens qui ont besoin d\u2019assistance consulaire d\u2019urgence \u00e0 l\u2019\u00e9tranger peuvent communiquer avec le Centre de surveillance et d\u2019intervention d\u2019urgence \u00e0 Ottawa, ouvert en tout temps et accessible de n\u2019importe o\u00f9 dans le monde, en composant \u00e0 frais vir\u00e9s le +1\u00a0613\u00a0996\u00a08885, ou en envoyant un courriel \u00e0\u00a0<a href=\"mailto:sos@international.gc.ca\">sos@international.gc.ca<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 13 f\u00e9vrier 2019 \u2013 Ottawa (Ontario) \u2013 Affaires mondiales Canada Dans les semaines \u00e0 venir, de nombreuses familles canadiennes profiteront du cong\u00e9 scolaire pour se rendre dans une destination internationale. Le gouvernement du Canada veut encourager tous les voyageurs \u00e0 bien s\u2019informer afin qu\u2019ils puissent passer un s\u00e9jour agr\u00e9able et en toute s\u00e9curit\u00e9 \u00e0 <a href=\"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/\" class=\"more-link\">&#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[20],"tags":[],"class_list":["post-1427","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conseils \u00e0 l\u2019intention des voyageurs canadiens : Voyager avec des enfants pendant la semaine de rel\u00e2che - Michael Chong<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conseils \u00e0 l\u2019intention des voyageurs canadiens : Voyager avec des enfants pendant la semaine de rel\u00e2che - Michael Chong\" \/>\n<meta property=\"og:description\" content=\"Le 13 f\u00e9vrier 2019 \u2013 Ottawa (Ontario) \u2013 Affaires mondiales Canada Dans les semaines \u00e0 venir, de nombreuses familles canadiennes profiteront du cong\u00e9 scolaire pour se rendre dans une destination internationale. Le gouvernement du Canada veut encourager tous les voyageurs \u00e0 bien s\u2019informer afin qu\u2019ils puissent passer un s\u00e9jour agr\u00e9able et en toute s\u00e9curit\u00e9 \u00e0 ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/\" \/>\n<meta property=\"og:site_name\" content=\"Michael Chong\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-22T20:44:35+00:00\" \/>\n<meta name=\"author\" content=\"admin437\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin437\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/\"},\"author\":{\"name\":\"admin437\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/f402ec3bbb11ca1e513f4971ab697c81\"},\"headline\":\"Conseils \u00e0 l\u2019intention des voyageurs canadiens : Voyager avec des enfants pendant la semaine de rel\u00e2che\",\"datePublished\":\"2019-02-22T20:44:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/\"},\"wordCount\":708,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/#organization\"},\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/\",\"url\":\"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/\",\"name\":\"Conseils \u00e0 l\u2019intention des voyageurs canadiens : Voyager avec des enfants pendant la semaine de rel\u00e2che - Michael Chong\",\"isPartOf\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/#website\"},\"datePublished\":\"2019-02-22T20:44:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/michaelchong.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils \u00e0 l\u2019intention des voyageurs canadiens : Voyager avec des enfants pendant la semaine de rel\u00e2che\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#website\",\"url\":\"https:\/\/michaelchong.ca\/fr\/\",\"name\":\"Michael Chong\",\"description\":\"D\u00e9put\u00e9 de Wellington-Halton Hills-Nord\",\"publisher\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/michaelchong.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#organization\",\"name\":\"Michael Chong\",\"url\":\"https:\/\/michaelchong.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/michaelchong.ca\/fr\/wp-content\/uploads\/2025\/05\/michael-chong-logo-2025-white-fr-1.png\",\"contentUrl\":\"https:\/\/michaelchong.ca\/fr\/wp-content\/uploads\/2025\/05\/michael-chong-logo-2025-white-fr-1.png\",\"width\":1142,\"height\":255,\"caption\":\"Michael Chong\"},\"image\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/f402ec3bbb11ca1e513f4971ab697c81\",\"name\":\"admin437\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ed1357ca834555c038a49b5887555419479fc5d6ebebc7ac134ff0131bbfa389?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ed1357ca834555c038a49b5887555419479fc5d6ebebc7ac134ff0131bbfa389?s=96&d=mm&r=g\",\"caption\":\"admin437\"},\"sameAs\":[\"http:\/\/michaelchong.ca\/fr\"],\"url\":\"https:\/\/michaelchong.ca\/fr\/author\/admin437\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conseils \u00e0 l\u2019intention des voyageurs canadiens : Voyager avec des enfants pendant la semaine de rel\u00e2che - Michael Chong","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/","og_locale":"fr_CA","og_type":"article","og_title":"Conseils \u00e0 l\u2019intention des voyageurs canadiens : Voyager avec des enfants pendant la semaine de rel\u00e2che - Michael Chong","og_description":"Le 13 f\u00e9vrier 2019 \u2013 Ottawa (Ontario) \u2013 Affaires mondiales Canada Dans les semaines \u00e0 venir, de nombreuses familles canadiennes profiteront du cong\u00e9 scolaire pour se rendre dans une destination internationale. Le gouvernement du Canada veut encourager tous les voyageurs \u00e0 bien s\u2019informer afin qu\u2019ils puissent passer un s\u00e9jour agr\u00e9able et en toute s\u00e9curit\u00e9 \u00e0 ...","og_url":"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/","og_site_name":"Michael Chong","article_published_time":"2019-02-22T20:44:35+00:00","author":"admin437","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin437","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/#article","isPartOf":{"@id":"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/"},"author":{"name":"admin437","@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/f402ec3bbb11ca1e513f4971ab697c81"},"headline":"Conseils \u00e0 l\u2019intention des voyageurs canadiens : Voyager avec des enfants pendant la semaine de rel\u00e2che","datePublished":"2019-02-22T20:44:35+00:00","mainEntityOfPage":{"@id":"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/"},"wordCount":708,"commentCount":0,"publisher":{"@id":"https:\/\/michaelchong.ca\/fr\/#organization"},"articleSection":["Nouvelles"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/","url":"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/","name":"Conseils \u00e0 l\u2019intention des voyageurs canadiens : Voyager avec des enfants pendant la semaine de rel\u00e2che - Michael Chong","isPartOf":{"@id":"https:\/\/michaelchong.ca\/fr\/#website"},"datePublished":"2019-02-22T20:44:35+00:00","breadcrumb":{"@id":"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/michaelchong.ca\/fr\/2019\/02\/22\/conseils-a-lintention-des-voyageurs-canadiens-voyager-avec-des-enfants-pendant-la-semaine-de-relache\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/michaelchong.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Conseils \u00e0 l\u2019intention des voyageurs canadiens : Voyager avec des enfants pendant la semaine de rel\u00e2che"}]},{"@type":"WebSite","@id":"https:\/\/michaelchong.ca\/fr\/#website","url":"https:\/\/michaelchong.ca\/fr\/","name":"Michael Chong","description":"D\u00e9put\u00e9 de Wellington-Halton Hills-Nord","publisher":{"@id":"https:\/\/michaelchong.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/michaelchong.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/michaelchong.ca\/fr\/#organization","name":"Michael Chong","url":"https:\/\/michaelchong.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/michaelchong.ca\/fr\/wp-content\/uploads\/2025\/05\/michael-chong-logo-2025-white-fr-1.png","contentUrl":"https:\/\/michaelchong.ca\/fr\/wp-content\/uploads\/2025\/05\/michael-chong-logo-2025-white-fr-1.png","width":1142,"height":255,"caption":"Michael Chong"},"image":{"@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/f402ec3bbb11ca1e513f4971ab697c81","name":"admin437","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ed1357ca834555c038a49b5887555419479fc5d6ebebc7ac134ff0131bbfa389?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed1357ca834555c038a49b5887555419479fc5d6ebebc7ac134ff0131bbfa389?s=96&d=mm&r=g","caption":"admin437"},"sameAs":["http:\/\/michaelchong.ca\/fr"],"url":"https:\/\/michaelchong.ca\/fr\/author\/admin437\/"}]}},"_links":{"self":[{"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/posts\/1427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/comments?post=1427"}],"version-history":[{"count":0,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/posts\/1427\/revisions"}],"wp:attachment":[{"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/media?parent=1427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/categories?post=1427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/tags?post=1427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}