{"id":1592,"date":"2020-12-03T12:07:59","date_gmt":"2020-12-03T17:07:59","guid":{"rendered":"http:\/\/michaelchong.ca\/fr\/?p=1592"},"modified":"2020-12-03T12:07:59","modified_gmt":"2020-12-03T17:07:59","slug":"compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho","status":"publish","type":"post","link":"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/","title":{"rendered":"Compte rendu : Le ministre du cabinet fant\u00f4me pour les affaires \u00e9trang\u00e8res, Michael Chong, discute avec l\u2019ambassadeur du Mexique au Canada, Son Excellence Juan Jos\u00e9 G\u00f3mez Camacho"},"content":{"rendered":"\n<p>POUR DIFFUSION IMM\u00c9DIATE<\/p>\n\n\n\n<p><strong>Ottawa (Ontario)<\/strong>&nbsp;<strong>\u2013<\/strong> Le mercredi&nbsp;2&nbsp;d\u00e9cembre&nbsp;2020, le ministre du cabinet fant\u00f4me conservateur pour les affaires \u00e9trang\u00e8res, Michael&nbsp;Chong, a tenu un appel t\u00e9l\u00e9phonique avec Son Excellence Juan&nbsp;Jos\u00e9&nbsp;G\u00f3mez Camacho, ambassadeur du Mexique au Canada, au sujet des relations canado\u2011mexicaines.<\/p>\n\n\n\n<p>Le d\u00e9put\u00e9&nbsp;Chong a abord\u00e9 plusieurs points avec l\u2019ambassadeur, notamment&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>la conviction des conservateurs que le Canada et le Mexique sont des partenaires strat\u00e9giques dans le cadre d\u2019une relation nord\u2011am\u00e9ricaine;<\/li><li>la volont\u00e9 des conservateurs d\u2019\u00e9largir et de resserrer les relations avec le Mexique, tant unilat\u00e9ralement qu\u2019au sein du partenariat nord\u2011am\u00e9ricain ainsi que dans le cadre de l\u2019accord commercial Canada\u2011\u00c9tats\u2011Unis\u2011Mexique nouvellement \u00e9tabli (AECUM); le Mexique est la 5<sup>e<\/sup>\u00a0destination pour les exportations de marchandises et la 10<sup>e<\/sup>\u00a0destination pour les investissements directs;<\/li><li>les solides liens entre les Canadiens et les Mexicains\u00a0: plus de 1,5\u00a0million de Canadiens se rendent habituellement au Mexique chaque ann\u00e9e, que ce soit en voyage d\u2019affaires ou d\u2019agr\u00e9ment, plus de 25\u00a0000\u00a0travailleurs agricoles saisonniers viennent au Canada pour travailler dans les fermes et plus de 20\u00a0000\u00a0\u00e9tudiants mexicains fr\u00e9quentent des \u00e9tablissements canadiens d\u2019enseignement postsecondaire;<\/li><li>le d\u00e9bat tenu r\u00e9cemment \u00e0 la Chambre des communes sur l\u2019approvisionnement en vaccins par le Canada dans le contexte de la pand\u00e9mie.<\/li><\/ul>\n\n\n\n<p>Son Excellence Juan&nbsp;Jos\u00e9&nbsp;G\u00f3mez&nbsp;Camacho et le d\u00e9put\u00e9&nbsp;Chong ont discut\u00e9 de la coop\u00e9ration entre le Canada et le Mexique durant la pand\u00e9mie, de la circulation sans visa entre le Canada et le Mexique et du nouvel AECUM. Ils ont convenu de rester en contact au sujet des relations canado\u2011mexicaines.<\/p>\n\n\n\n<p class=\"has-text-align-center\">-30-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>POUR DIFFUSION IMM\u00c9DIATE Ottawa (Ontario)&nbsp;\u2013 Le mercredi&nbsp;2&nbsp;d\u00e9cembre&nbsp;2020, le ministre du cabinet fant\u00f4me conservateur pour les affaires \u00e9trang\u00e8res, Michael&nbsp;Chong, a tenu un appel t\u00e9l\u00e9phonique avec Son Excellence Juan&nbsp;Jos\u00e9&nbsp;G\u00f3mez Camacho, ambassadeur du Mexique au Canada, au sujet des relations canado\u2011mexicaines. Le d\u00e9put\u00e9&nbsp;Chong a abord\u00e9 plusieurs points avec l\u2019ambassadeur, notamment&nbsp;: la conviction des conservateurs que le Canada et <a href=\"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/\" class=\"more-link\">&#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[20],"tags":[],"class_list":["post-1592","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Compte rendu : Le ministre du cabinet fant\u00f4me pour les affaires \u00e9trang\u00e8res, Michael Chong, discute avec l\u2019ambassadeur du Mexique au Canada, Son Excellence Juan Jos\u00e9 G\u00f3mez Camacho - Michael Chong<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compte rendu : Le ministre du cabinet fant\u00f4me pour les affaires \u00e9trang\u00e8res, Michael Chong, discute avec l\u2019ambassadeur du Mexique au Canada, Son Excellence Juan Jos\u00e9 G\u00f3mez Camacho - Michael Chong\" \/>\n<meta property=\"og:description\" content=\"POUR DIFFUSION IMM\u00c9DIATE Ottawa (Ontario)&nbsp;\u2013 Le mercredi&nbsp;2&nbsp;d\u00e9cembre&nbsp;2020, le ministre du cabinet fant\u00f4me conservateur pour les affaires \u00e9trang\u00e8res, Michael&nbsp;Chong, a tenu un appel t\u00e9l\u00e9phonique avec Son Excellence Juan&nbsp;Jos\u00e9&nbsp;G\u00f3mez Camacho, ambassadeur du Mexique au Canada, au sujet des relations canado\u2011mexicaines. Le d\u00e9put\u00e9&nbsp;Chong a abord\u00e9 plusieurs points avec l\u2019ambassadeur, notamment&nbsp;: la conviction des conservateurs que le Canada et ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/\" \/>\n<meta property=\"og:site_name\" content=\"Michael Chong\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-03T17:07:59+00:00\" \/>\n<meta name=\"author\" content=\"admin437\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin437\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/\"},\"author\":{\"name\":\"admin437\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/f402ec3bbb11ca1e513f4971ab697c81\"},\"headline\":\"Compte rendu : Le ministre du cabinet fant\u00f4me pour les affaires \u00e9trang\u00e8res, Michael Chong, discute avec l\u2019ambassadeur du Mexique au Canada, Son Excellence Juan Jos\u00e9 G\u00f3mez Camacho\",\"datePublished\":\"2020-12-03T17:07:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/\"},\"wordCount\":330,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/#organization\"},\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/\",\"url\":\"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/\",\"name\":\"Compte rendu : Le ministre du cabinet fant\u00f4me pour les affaires \u00e9trang\u00e8res, Michael Chong, discute avec l\u2019ambassadeur du Mexique au Canada, Son Excellence Juan Jos\u00e9 G\u00f3mez Camacho - Michael Chong\",\"isPartOf\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/#website\"},\"datePublished\":\"2020-12-03T17:07:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/michaelchong.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compte rendu : Le ministre du cabinet fant\u00f4me pour les affaires \u00e9trang\u00e8res, Michael Chong, discute avec l\u2019ambassadeur du Mexique au Canada, Son Excellence Juan Jos\u00e9 G\u00f3mez Camacho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#website\",\"url\":\"https:\/\/michaelchong.ca\/fr\/\",\"name\":\"Michael Chong\",\"description\":\"D\u00e9put\u00e9 de Wellington-Halton Hills-Nord\",\"publisher\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/michaelchong.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#organization\",\"name\":\"Michael Chong\",\"url\":\"https:\/\/michaelchong.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/michaelchong.ca\/fr\/wp-content\/uploads\/2025\/05\/michael-chong-logo-2025-white-fr-1.png\",\"contentUrl\":\"https:\/\/michaelchong.ca\/fr\/wp-content\/uploads\/2025\/05\/michael-chong-logo-2025-white-fr-1.png\",\"width\":1142,\"height\":255,\"caption\":\"Michael Chong\"},\"image\":{\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/f402ec3bbb11ca1e513f4971ab697c81\",\"name\":\"admin437\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ed1357ca834555c038a49b5887555419479fc5d6ebebc7ac134ff0131bbfa389?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ed1357ca834555c038a49b5887555419479fc5d6ebebc7ac134ff0131bbfa389?s=96&d=mm&r=g\",\"caption\":\"admin437\"},\"sameAs\":[\"http:\/\/michaelchong.ca\/fr\"],\"url\":\"https:\/\/michaelchong.ca\/fr\/author\/admin437\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Compte rendu : Le ministre du cabinet fant\u00f4me pour les affaires \u00e9trang\u00e8res, Michael Chong, discute avec l\u2019ambassadeur du Mexique au Canada, Son Excellence Juan Jos\u00e9 G\u00f3mez Camacho - Michael Chong","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/","og_locale":"fr_CA","og_type":"article","og_title":"Compte rendu : Le ministre du cabinet fant\u00f4me pour les affaires \u00e9trang\u00e8res, Michael Chong, discute avec l\u2019ambassadeur du Mexique au Canada, Son Excellence Juan Jos\u00e9 G\u00f3mez Camacho - Michael Chong","og_description":"POUR DIFFUSION IMM\u00c9DIATE Ottawa (Ontario)&nbsp;\u2013 Le mercredi&nbsp;2&nbsp;d\u00e9cembre&nbsp;2020, le ministre du cabinet fant\u00f4me conservateur pour les affaires \u00e9trang\u00e8res, Michael&nbsp;Chong, a tenu un appel t\u00e9l\u00e9phonique avec Son Excellence Juan&nbsp;Jos\u00e9&nbsp;G\u00f3mez Camacho, ambassadeur du Mexique au Canada, au sujet des relations canado\u2011mexicaines. Le d\u00e9put\u00e9&nbsp;Chong a abord\u00e9 plusieurs points avec l\u2019ambassadeur, notamment&nbsp;: la conviction des conservateurs que le Canada et ...","og_url":"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/","og_site_name":"Michael Chong","article_published_time":"2020-12-03T17:07:59+00:00","author":"admin437","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin437","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/#article","isPartOf":{"@id":"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/"},"author":{"name":"admin437","@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/f402ec3bbb11ca1e513f4971ab697c81"},"headline":"Compte rendu : Le ministre du cabinet fant\u00f4me pour les affaires \u00e9trang\u00e8res, Michael Chong, discute avec l\u2019ambassadeur du Mexique au Canada, Son Excellence Juan Jos\u00e9 G\u00f3mez Camacho","datePublished":"2020-12-03T17:07:59+00:00","mainEntityOfPage":{"@id":"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/"},"wordCount":330,"commentCount":0,"publisher":{"@id":"https:\/\/michaelchong.ca\/fr\/#organization"},"articleSection":["Nouvelles"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/","url":"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/","name":"Compte rendu : Le ministre du cabinet fant\u00f4me pour les affaires \u00e9trang\u00e8res, Michael Chong, discute avec l\u2019ambassadeur du Mexique au Canada, Son Excellence Juan Jos\u00e9 G\u00f3mez Camacho - Michael Chong","isPartOf":{"@id":"https:\/\/michaelchong.ca\/fr\/#website"},"datePublished":"2020-12-03T17:07:59+00:00","breadcrumb":{"@id":"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/michaelchong.ca\/fr\/2020\/12\/03\/compte-rendu-le-ministre-du-cabinet-fantome-pour-les-affaires-etrangeres-michael-chong-discute-avec-lambassadeur-du-mexique-au-canada-son-excellence-juan-jose-gomez-camacho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/michaelchong.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Compte rendu : Le ministre du cabinet fant\u00f4me pour les affaires \u00e9trang\u00e8res, Michael Chong, discute avec l\u2019ambassadeur du Mexique au Canada, Son Excellence Juan Jos\u00e9 G\u00f3mez Camacho"}]},{"@type":"WebSite","@id":"https:\/\/michaelchong.ca\/fr\/#website","url":"https:\/\/michaelchong.ca\/fr\/","name":"Michael Chong","description":"D\u00e9put\u00e9 de Wellington-Halton Hills-Nord","publisher":{"@id":"https:\/\/michaelchong.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/michaelchong.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/michaelchong.ca\/fr\/#organization","name":"Michael Chong","url":"https:\/\/michaelchong.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/michaelchong.ca\/fr\/wp-content\/uploads\/2025\/05\/michael-chong-logo-2025-white-fr-1.png","contentUrl":"https:\/\/michaelchong.ca\/fr\/wp-content\/uploads\/2025\/05\/michael-chong-logo-2025-white-fr-1.png","width":1142,"height":255,"caption":"Michael Chong"},"image":{"@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/f402ec3bbb11ca1e513f4971ab697c81","name":"admin437","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/michaelchong.ca\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ed1357ca834555c038a49b5887555419479fc5d6ebebc7ac134ff0131bbfa389?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed1357ca834555c038a49b5887555419479fc5d6ebebc7ac134ff0131bbfa389?s=96&d=mm&r=g","caption":"admin437"},"sameAs":["http:\/\/michaelchong.ca\/fr"],"url":"https:\/\/michaelchong.ca\/fr\/author\/admin437\/"}]}},"_links":{"self":[{"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/posts\/1592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/comments?post=1592"}],"version-history":[{"count":0,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/posts\/1592\/revisions"}],"wp:attachment":[{"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/media?parent=1592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/categories?post=1592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/michaelchong.ca\/fr\/wp-json\/wp\/v2\/tags?post=1592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}